{"id":81,"count":1,"description":"","link":"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/","name":"#OlympicDebut","slug":"olympicdebut","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#OlympicDebut Archives - Sports Buddy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#OlympicDebut Archives - Sports Buddy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/\" \/>\n<meta property=\"og:site_name\" content=\"Sports Buddy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SportsBuddy_Me\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/\",\"url\":\"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/\",\"name\":\"#OlympicDebut Archives - Sports Buddy\",\"isPartOf\":{\"@id\":\"https:\/\/sportsbuddy.me\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sportsbuddy.me\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#OlympicDebut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sportsbuddy.me\/blog\/#website\",\"url\":\"https:\/\/sportsbuddy.me\/blog\/\",\"name\":\"Sports Buddy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sportsbuddy.me\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sportsbuddy.me\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sportsbuddy.me\/blog\/#organization\",\"name\":\"Sports Buddy\",\"url\":\"https:\/\/sportsbuddy.me\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sportsbuddy.me\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sportsbuddy.me\/blog\/wp-content\/uploads\/2024\/07\/Torch_Bearer_02.png\",\"contentUrl\":\"https:\/\/sportsbuddy.me\/blog\/wp-content\/uploads\/2024\/07\/Torch_Bearer_02.png\",\"width\":1651,\"height\":1651,\"caption\":\"Sports Buddy\"},\"image\":{\"@id\":\"https:\/\/sportsbuddy.me\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sportsbuddyme\",\"https:\/\/x.com\/SportsBuddy_Me\",\"https:\/\/www.instagram.com\/sportsbuddy_me\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#OlympicDebut Archives - Sports Buddy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/","og_locale":"en_US","og_type":"article","og_title":"#OlympicDebut Archives - Sports Buddy","og_url":"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/","og_site_name":"Sports Buddy","twitter_card":"summary_large_image","twitter_site":"@SportsBuddy_Me","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/","url":"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/","name":"#OlympicDebut Archives - Sports Buddy","isPartOf":{"@id":"https:\/\/sportsbuddy.me\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sportsbuddy.me\/blog\/tag\/olympicdebut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sportsbuddy.me\/blog\/"},{"@type":"ListItem","position":2,"name":"#OlympicDebut"}]},{"@type":"WebSite","@id":"https:\/\/sportsbuddy.me\/blog\/#website","url":"https:\/\/sportsbuddy.me\/blog\/","name":"Sports Buddy","description":"","publisher":{"@id":"https:\/\/sportsbuddy.me\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sportsbuddy.me\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sportsbuddy.me\/blog\/#organization","name":"Sports Buddy","url":"https:\/\/sportsbuddy.me\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sportsbuddy.me\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/sportsbuddy.me\/blog\/wp-content\/uploads\/2024\/07\/Torch_Bearer_02.png","contentUrl":"https:\/\/sportsbuddy.me\/blog\/wp-content\/uploads\/2024\/07\/Torch_Bearer_02.png","width":1651,"height":1651,"caption":"Sports Buddy"},"image":{"@id":"https:\/\/sportsbuddy.me\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sportsbuddyme","https:\/\/x.com\/SportsBuddy_Me","https:\/\/www.instagram.com\/sportsbuddy_me\/"]}]}},"_links":{"self":[{"href":"https:\/\/sportsbuddy.me\/blog\/wp-json\/wp\/v2\/tags\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportsbuddy.me\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sportsbuddy.me\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sportsbuddy.me\/blog\/wp-json\/wp\/v2\/posts?tags=81"},{"href":"https:\/\/sportsbuddy.me\/blog\/wp-json\/wp\/v2\/podcast?tags=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}